{"id":251,"count":1,"description":"","link":"https:\/\/odiceabogados.com\/en\/tag\/caudal-hereditario\/","name":"Caudal Hereditario","slug":"caudal-hereditario","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/odiceabogados.com\/en\/wp-json\/wp\/v2\/tags\/251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odiceabogados.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/odiceabogados.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/odiceabogados.com\/en\/wp-json\/wp\/v2\/posts?tags=251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}